{"id":222948,"date":"2021-04-18T00:00:00","date_gmt":"2021-04-18T00:00:00","guid":{"rendered":"http:\/\/unadeca.ac.cr\/teologia\/?p=222948"},"modified":"2021-04-10T21:36:16","modified_gmt":"2021-04-10T21:36:16","slug":"desafio-obedecer-a-dios-para-que-se-cumplan-sus-promesas-de-bendicion","status":"publish","type":"post","link":"http:\/\/unadeca.ac.cr\/teologia\/2021\/04\/18\/desafio-obedecer-a-dios-para-que-se-cumplan-sus-promesas-de-bendicion\/","title":{"rendered":"DESAF\u00cdO: OBEDECER A DIOS PARA QUE SE CUMPLAN SUS PROMESAS DE BENDICI\u00d3N"},"content":{"rendered":"\n<h2 class=\"has-text-align-center wp-block-heading\">LEAMOS HOY 18 DE ABRIL ZACAR\u00cdAS 8<\/h2>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote class=\"has-text-color has-vivid-red-color\"><p><strong>VERS\u00cdCULO PARA MEMORIZAR:<\/strong> \u201cLo que ustedes deben hacer es decirse la verdad, y juzgar en sus tribunales con la verdad y la justicia. \u00a1Eso trae la paz! No maquinen el mal contra su pr\u00f3jimo, ni sean dados al falso testimonio, porque yo aborrezco todo eso, afirma el SE\u00d1OR.\u201d<\/p><cite>ZACAR\u00cdAS 8:16,17<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">COMENTARIO HIST\u00d3RICO DE ZACAR\u00cdAS 8<\/h3>\n\n\n\n<p>Este cap\u00edtulo recalca que la obediencia era el requisito indispensable para que el remanente pueda establecerse en forma definitiva en la tierra prometida, y que puedan recibir las bendiciones de restauraci\u00f3n. Dios requiere que la verdad y la justicia se establezcan en los tribunales. Dios pide que los abogados, fiscales y jueces, interpreten las leyes para hacer justicia. Dios desea que el trato con el pr\u00f3jimo sea el adecuado para que exista la verdadera paz. <\/p>\n\n\n\n<p>SEAMOS INSTRUMENTOS DE PAZ.- Dios anhela que nuestra presencia en este mundo sirva para establecer puentes de reconciliaci\u00f3n, que seamos expertos en apaciguar los ambientes caldeados por la intolerancia. <\/p>\n\n\n\n<p>NO TRAMEMOS EL MAL CONTRA NUESTRO PR\u00d3JIMO.- Dios expresa repetida veces es su Palabra, que reprueba cuando se maquinan actos de maldad o de da\u00f1ar la honorabilidad de nuestros pr\u00f3jimos.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">CITA SELECTA <\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEstas promesas les eran hechas a condici\u00f3n de que obedecieran. No deb\u00edan repetirse los pecados que hab\u00edan caracterizado a los israelitas antes del cautiverio. El Se\u00f1or exhort\u00f3 a los que estaban reedificando: \u201cJuzgad juicio verdadero, y haced misericordia y piedad cada cual con su hermano: no agravi\u00e9is a la viuda, ni al hu\u00e9rfano, ni al extranjero, ni al pobre; ni ninguno piense mal en su coraz\u00f3n contra su hermano.\u201d \u201cHablad verdad cada cual con su pr\u00f3jimo; juzgad en vuestras puertas verdad y juicio de paz.\u201d Zacar\u00edas 7:9, 10; 8:16. Ricas eran las recompensas, tanto temporales como espirituales, que se promet\u00edan a quienes pusieran en pr\u00e1ctica estos principios de justicia. El Se\u00f1or declar\u00f3: \u201cHabr\u00e1 simiente de paz; la vid dar\u00e1 su fruto, y dar\u00e1 su producto la tierra, y los cielos dar\u00e1n su roc\u00edo; y har\u00e9 que el resto de este pueblo posea todo esto. Y ser\u00e1 que como fuisteis maldici\u00f3n entre las gentes, oh casa de Jud\u00e1 y casa de Israel, as\u00ed os salvar\u00e9, y ser\u00e9is bendici\u00f3n.\u201d Zacar\u00edas 8:12, 13. <\/p><cite>(PR 520).<\/cite><\/blockquote>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">ORACI\u00d3N<\/h3>\n\n\n\n<p>PADRE NUESTRO. TE PEDIMOS PERD\u00d3N, PORQUE NO HEMOS OBEDECIDO TUS MANDATOS, Y HEMOS PERDIDO LAS BENDICIONES PROMETIDAS. TE SUPLICAMOS QUE NOS AYUDES SIEMPRE A DECIR LA VERDAD Y SOSTENER LA JUSTICIA, PARA QUE SEAMOS INSTRUMENTOS DE PAZ. POR JES\u00daS, AM\u00c9N.<\/p>\n\n\n\n<iframe width=\"100%\" height=\"166\" scrolling=\"no\" frameborder=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/1026791287&#038;color=%23ff5500&#038;auto_play=true&#038;hide_related=false&#038;show_comments=true&#038;show_user=true&#038;show_reposts=false&#038;show_teaser=true\"><\/iframe><div style=\"font-size: 10px; color: #cccccc;line-break: anywhere;word-break: normal;overflow: hidden;white-space: nowrap;text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif;font-weight: 100;\"><a href=\"https:\/\/soundcloud.com\/centro-white-unadeca-1\" title=\"Escuela de Teolog\u00eda, UNADECA\" target=\"_blank\" style=\"color: #cccccc; text-decoration: none;\" rel=\"noopener\">Escuela de Teolog\u00eda, UNADECA<\/a> \u00b7 <a href=\"https:\/\/soundcloud.com\/centro-white-unadeca-1\/20210418-zacarias-8\" title=\"20210418 Zacarias 8\" target=\"_blank\" style=\"color: #cccccc; text-decoration: none;\" rel=\"noopener\">20210418 Zacarias 8<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>LEAMOS HOY 18 DE ABRIL ZACAR\u00cdAS 8.<br \/>\nVERS\u00cdCULO PARA MEMORIZAR: \u201cLo que ustedes deben hacer es decirse la verdad, y juzgar en sus tribunales con la verdad y la justicia. \u00a1Eso trae la paz! No maquinen el mal contra su pr\u00f3jimo, ni sean dados al falso testimonio, porque yo aborrezco todo eso, afirma el SE\u00d1OR.\u201d (Vers. 16, 17). <\/p>\n","protected":false},"author":1,"featured_media":222337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-222948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atentos"],"_links":{"self":[{"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/posts\/222948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/comments?post=222948"}],"version-history":[{"count":1,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/posts\/222948\/revisions"}],"predecessor-version":[{"id":222949,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/posts\/222948\/revisions\/222949"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/media\/222337"}],"wp:attachment":[{"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/media?parent=222948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/categories?post=222948"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/tags?post=222948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}