{"id":222972,"date":"2021-04-27T00:00:00","date_gmt":"2021-04-27T00:00:00","guid":{"rendered":"http:\/\/unadeca.ac.cr\/teologia\/?p=222972"},"modified":"2021-04-26T01:17:30","modified_gmt":"2021-04-26T01:17:30","slug":"pedido-pedir-al-senor-que-nuestro-nombre-y-nuestros-actos-esten-en-el-libro-de-las-memorias","status":"publish","type":"post","link":"http:\/\/unadeca.ac.cr\/teologia\/2021\/04\/27\/pedido-pedir-al-senor-que-nuestro-nombre-y-nuestros-actos-esten-en-el-libro-de-las-memorias\/","title":{"rendered":"PEDIDO: PEDIR AL SE\u00d1OR QUE NUESTRO NOMBRE Y NUESTROS ACTOS EST\u00c9N EN EL LIBRO DE LAS MEMORIAS"},"content":{"rendered":"\n<h2 class=\"has-text-align-center wp-block-heading\">\u00a0LEAMOS HOY 27 DE ABRIL MALAQU\u00cdAS 3<\/h2>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote class=\"has-text-color has-luminous-vivid-orange-color\"><p>VERS\u00cdCULO PARA MEMORIZAR: \u201cEntonces los que tem\u00edan a Jehov\u00e1 hablaron cada uno a su compa\u00f1ero; y Jehov\u00e1 escuch\u00f3 y oy\u00f3, y fue escrito libro de memoria delante de \u00e9l para los que temen a Jehov\u00e1, y para los que piensan en su nombre.\u201d (Vers. 16).<\/p><cite>MALAQU\u00cdAS 3:16<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">COMENTARIO HIST\u00d3RICO DE MALAQU\u00cdAS 3.<\/h3>\n\n\n\n<p>El cap\u00edtulo 3, presenta la profec\u00eda de la aparici\u00f3n de Juan el Bautista, el mensajero de Cristo, quien preparar\u00eda el camino del Mes\u00edas. El segundo tema que se desarrolla es sobre la fidelidad a Dios en la devoluci\u00f3n de los diezmos y las ofrendas. Se amonesta al pueblo a devolver los diezmos y las ofrendas, que hab\u00edan sido retenidos, de lo contrar\u00eda ser\u00edan considerados LADRONES. Esta deshonestidad los privar\u00eda de las bendiciones que Dios deseaba otorgarles. Es necesario comprender que las bendiciones son de dos naturalezas: espirituales y materiales. Un grupo acept\u00f3 el mensaje de reprensi\u00f3n, apelaron a sus amigos y vecinos para que ellos tambi\u00e9n sean fieles en la devoluci\u00f3n de los diezmos y las ofrendas. Como recompensa, Dios anot\u00f3 en el libro de las memorias este acto de intercesi\u00f3n. <\/p>\n\n\n\n<p>QUE NUESTRA CONVERSACI\u00d3N SEA ELEVADA Y ESPIRITUAL.- \u201cCuando los que se re\u00fanen tienen el amor de Dios ardiendo en sus corazones, cuando nada se dice o hace para agraviar el Esp\u00edritu Santo de Dios, sino que se lo considera un hu\u00e9sped bienvenido, entonces Dios es honrado y los que se re\u00fanan ser\u00e1n refrigerados y fortalecidos.\u201d (CM, 322).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">CITA SELECTA.<\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cDelante de Dios est\u00e1 escrito \u201cun libro de memoria\u201d, en el cual quedan consignadas las buenas obras de \u201clos que temen a Jehov\u00e1, y de los que piensan en su nombre\u201d. Malaqu\u00edas 3:16 (VM). Sus palabras de fe, sus actos de amor est\u00e1n registrados en el cielo. A esto se refiere Nehem\u00edas cuando dice: \u201cAcu\u00e9rdate de m\u00ed, oh Dios m\u00edo, [&#8230;] y no borres mis obras piadosas que he hecho por la Casa de mi Dios!\u201d En el \u201clibro de memoria\u201d de Dios, todo acto de justicia est\u00e1 inmortalizado. Toda tentaci\u00f3n resistida, todo pecado vencido, toda palabra de tierna compasi\u00f3n est\u00e1n fielmente consignados, y apuntados tambi\u00e9n todo acto de sacrificio, todo padecimiento y todo pesar sufridos por causa de Cristo. El salmista dice: \u201cT\u00fa cuentas los pasos de mi vida errante: pon mis l\u00e1grimas en tu redoma: \u00bfno est\u00e1n en tu libro?\u201d <\/p><cite>(CS 473).<\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">OREMOS: <\/h3>\n\n\n\n<p>DIOS NUESTRO Y PADRE ETERNO. TE PEDIMOS PERD\u00d3N POR NO DEVOLVERTE EL DIEZMO Y LAS OFRENDAS. NOS COMPROMETEMOS A HABLAR A NUESTRAS FAMILIAS, AMIGOS Y HERMANOS PARA QUE TE DEVUELVAN LO QUE TE CORRESPONDE. POR JES\u00daS, AM\u00c9N.<\/p>\n\n\n\n<iframe width=\"100%\" height=\"166\" scrolling=\"no\" frameborder=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/1036660711&#038;color=%23ff5500&#038;auto_play=true&#038;hide_related=false&#038;show_comments=true&#038;show_user=true&#038;show_reposts=false&#038;show_teaser=true\"><\/iframe><div style=\"font-size: 10px; color: #cccccc;line-break: anywhere;word-break: normal;overflow: hidden;white-space: nowrap;text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif;font-weight: 100;\"><a href=\"https:\/\/soundcloud.com\/centro-white-unadeca-1\" title=\"Escuela de Teolog\u00eda, UNADECA\" target=\"_blank\" style=\"color: #cccccc; text-decoration: none;\" rel=\"noopener\">Escuela de Teolog\u00eda, UNADECA<\/a> \u00b7 <a href=\"https:\/\/soundcloud.com\/centro-white-unadeca-1\/20210427-malaquias-3\" title=\"20210427 Malaquias 3\" target=\"_blank\" style=\"color: #cccccc; text-decoration: none;\" rel=\"noopener\">20210427 Malaquias 3<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p> LEAMOS HOY 27 DE ABRIL MALAQU\u00cdAS 3.<br \/>\nVERS\u00cdCULO PARA MEMORIZAR: \u201cEntonces los que tem\u00edan a Jehov\u00e1 hablaron cada uno a su compa\u00f1ero; y Jehov\u00e1 escuch\u00f3 y oy\u00f3, y fue escrito libro de memoria delante de \u00e9l para los que temen a Jehov\u00e1, y para los que piensan en su nombre.\u201d (Vers. 16).<\/p>\n","protected":false},"author":1,"featured_media":222337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-222972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atentos"],"_links":{"self":[{"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/posts\/222972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/comments?post=222972"}],"version-history":[{"count":1,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/posts\/222972\/revisions"}],"predecessor-version":[{"id":222973,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/posts\/222972\/revisions\/222973"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/media\/222337"}],"wp:attachment":[{"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/media?parent=222972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/categories?post=222972"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/unadeca.ac.cr\/teologia\/wp-json\/wp\/v2\/tags?post=222972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}